{"id":5446,"date":"2020-12-22T18:30:24","date_gmt":"2020-12-22T21:30:24","guid":{"rendered":"https:\/\/dmsdesign.com.br\/portfolio\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/"},"modified":"2024-08-30T11:28:18","modified_gmt":"2024-08-30T14:28:18","slug":"fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity","status":"publish","type":"portfolio","link":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/","title":{"rendered":"Fernando Argollo &#8211; Semi-Jewelry &#8211; Corporate Visual Identity"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Creation of complete corporate visual identity<\/p>\n","protected":false},"author":1,"featured_media":4831,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"portfolio-types":[327,328,332,331],"class_list":["post-5446","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-brand-identity","portfolio-types-offline-en","portfolio-types-online-en","portfolio-types-social-media"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Creation of complete corporate visual identity\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"dmsdesign\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<!-- Google tag (gtag.js) -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-ZWG5QVG1LL\"><\/script>\n<script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-ZWG5QVG1LL');\n<\/script>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-types\\\/brand-identity\\\/#listItem\",\"name\":\"Brand Identity\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-types\\\/brand-identity\\\/#listItem\",\"position\":2,\"name\":\"Brand Identity\",\"item\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-types\\\/brand-identity\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#listItem\",\"name\":\"Fernando Argollo &#8211; Semi-Jewelry &#8211; Corporate Visual Identity\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#listItem\",\"position\":3,\"name\":\"Fernando Argollo &#8211; Semi-Jewelry &#8211; Corporate Visual Identity\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-types\\\/brand-identity\\\/#listItem\",\"name\":\"Brand Identity\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/#organization\",\"name\":\"DMS Design\",\"description\":\"DMS Design offers creative and distinctive solutions for your company. We specialize in digital and print media, as well as corporate identity, including websites, presentations, brochures, catalogs, manuals, advertisements, logos, and social media.\",\"url\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dmsdesign.com.br\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/logo-dmsdesign-menor.png\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#organizationLogo\",\"width\":400,\"height\":116},\"image\":{\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/author\\\/dmsdesign\\\/#author\",\"url\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/author\\\/dmsdesign\\\/\",\"name\":\"dmsdesign\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75d9dcab84f389736a1dfff615720fbeb95722063a86a8b0c10a176b33a09bba?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"dmsdesign\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#webpage\",\"url\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/\",\"name\":\"Fernando Argollo \\u2013 Semi-Jewelry \\u2013 Corporate Visual Identity | DMS Design\",\"description\":\"Creation of complete corporate visual identity\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/author\\\/dmsdesign\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/author\\\/dmsdesign\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/dmsdesign.com.br\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/dmsdesign-thumb-fernando-argollo-e1610336094511.jpg\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#mainImage\",\"width\":665,\"height\":664},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/portfolio-item\\\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\\\/#mainImage\"},\"datePublished\":\"2020-12-22T18:30:24-03:00\",\"dateModified\":\"2024-08-30T11:28:18-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/\",\"name\":\"DMS Design\",\"description\":\"DMS Design offers creative and distinctive solutions for your company. We specialize in digital and print media, as well as corporate identity, including websites, presentations, brochures, catalogs, manuals, advertisements, logos, and social media.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/dmsdesign.com.br\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fernando Argollo \u2013 Semi-Jewelry \u2013 Corporate Visual Identity | DMS Design","description":"Creation of complete corporate visual identity","canonical_url":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Google tag (gtag.js) --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-ZWG5QVG1LL\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag('js', new Date());\n\n  gtag('config', 'G-ZWG5QVG1LL');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/dmsdesign.com.br\/en\/#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/dmsdesign.com.br\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-types\/brand-identity\/#listItem","name":"Brand Identity"}},{"@type":"ListItem","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-types\/brand-identity\/#listItem","position":2,"name":"Brand Identity","item":"https:\/\/dmsdesign.com.br\/en\/portfolio-types\/brand-identity\/","nextItem":{"@type":"ListItem","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#listItem","name":"Fernando Argollo &#8211; Semi-Jewelry &#8211; Corporate Visual Identity"},"previousItem":{"@type":"ListItem","@id":"https:\/\/dmsdesign.com.br\/en\/#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#listItem","position":3,"name":"Fernando Argollo &#8211; Semi-Jewelry &#8211; Corporate Visual Identity","previousItem":{"@type":"ListItem","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-types\/brand-identity\/#listItem","name":"Brand Identity"}}]},{"@type":"Organization","@id":"https:\/\/dmsdesign.com.br\/en\/#organization","name":"DMS Design","description":"DMS Design offers creative and distinctive solutions for your company. We specialize in digital and print media, as well as corporate identity, including websites, presentations, brochures, catalogs, manuals, advertisements, logos, and social media.","url":"https:\/\/dmsdesign.com.br\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/dmsdesign.com.br\/wp-content\/uploads\/2018\/12\/logo-dmsdesign-menor.png","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#organizationLogo","width":400,"height":116},"image":{"@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/dmsdesign.com.br\/en\/author\/dmsdesign\/#author","url":"https:\/\/dmsdesign.com.br\/en\/author\/dmsdesign\/","name":"dmsdesign","image":{"@type":"ImageObject","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/75d9dcab84f389736a1dfff615720fbeb95722063a86a8b0c10a176b33a09bba?s=96&d=mm&r=g","width":96,"height":96,"caption":"dmsdesign"}},{"@type":"WebPage","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#webpage","url":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/","name":"Fernando Argollo \u2013 Semi-Jewelry \u2013 Corporate Visual Identity | DMS Design","description":"Creation of complete corporate visual identity","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/dmsdesign.com.br\/en\/#website"},"breadcrumb":{"@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#breadcrumblist"},"author":{"@id":"https:\/\/dmsdesign.com.br\/en\/author\/dmsdesign\/#author"},"creator":{"@id":"https:\/\/dmsdesign.com.br\/en\/author\/dmsdesign\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/dmsdesign.com.br\/wp-content\/uploads\/2020\/12\/dmsdesign-thumb-fernando-argollo-e1610336094511.jpg","@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#mainImage","width":665,"height":664},"primaryImageOfPage":{"@id":"https:\/\/dmsdesign.com.br\/en\/portfolio-item\/fernando-argollo-semi-jewelry-and-arrangements-corporate-visual-identity\/#mainImage"},"datePublished":"2020-12-22T18:30:24-03:00","dateModified":"2024-08-30T11:28:18-03:00"},{"@type":"WebSite","@id":"https:\/\/dmsdesign.com.br\/en\/#website","url":"https:\/\/dmsdesign.com.br\/en\/","name":"DMS Design","description":"DMS Design offers creative and distinctive solutions for your company. We specialize in digital and print media, as well as corporate identity, including websites, presentations, brochures, catalogs, manuals, advertisements, logos, and social media.","inLanguage":"en-US","publisher":{"@id":"https:\/\/dmsdesign.com.br\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"5446","title":null,"description":"#post_excerpt","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-30 14:25:46","updated":"2025-06-06 03:42:00","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/portfolio\/5446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/comments?post=5446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/media\/4831"}],"wp:attachment":[{"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/media?parent=5446"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/dmsdesign.com.br\/en\/wp-json\/wp\/v2\/portfolio-types?post=5446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}